{"id":37859,"date":"2025-06-05T14:46:02","date_gmt":"2025-06-05T12:46:02","guid":{"rendered":"https:\/\/www.riu.com\/blog\/?p=37859"},"modified":"2026-02-26T16:03:04","modified_gmt":"2026-02-26T15:03:04","slug":"riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025","status":"publish","type":"post","link":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/","title":{"rendered":"Wie bek\u00e4mpft RIU Hotels die Plastikverschmutzung am Weltumwelttag?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">RIU Hotels schlie\u00dft sich am 5. Juni 2025 der UN-Kampagne <strong>#BeatPlasticPollution<\/strong> an und bekr\u00e4ftigt damit sein Engagement f\u00fcr den <strong>nachhaltigen Tourismus<\/strong>. Durch die Strategie <strong>Proudly Committed<\/strong> hat die Kette seit 2021 eine <strong>Reduzierung von Einwegkunststoffen um 27,7 %<\/strong> pro Aufenthalt erreicht, indem sie Einweg-Amenities eliminiert und ihre Lieferkette optimiert hat.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was beinhaltet das Engagement von RIU im Rahmen der \u201eProudly Committed\u201c-Strategie?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei <strong>RIU Hotels<\/strong> verstehen wir, dass der Kampf gegen die <strong>Plastikverschmutzung<\/strong> kein vor\u00fcbergehender Trend ist, sondern eine zentrale S\u00e4ule unserer Unternehmensphilosophie. Unsere <a href=\"https:\/\/www.riu.com\/de\/proudly-committed#proudly-committed\" target=\"_blank\" rel=\"noreferrer noopener\">Proudly Committed<\/a>-Strategie leitet jede unserer Ma\u00dfnahmen zum Schutz der Reiseziele, an denen wir t\u00e4tig sind.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a981c5f0023d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a981c5f0023d\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/05062025-Foto07_Botellas-1600x900.jpg\" alt=\"\" class=\"wp-image-37901\" srcset=\"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/05062025-Foto07_Botellas-1600x900.jpg 1600w, https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/05062025-Foto07_Botellas-600x337.jpg 600w, https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/05062025-Foto07_Botellas-768x432.jpg 768w, https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/05062025-Foto07_Botellas-1536x864.jpg 1536w, https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/05062025-Foto07_Botellas-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Wir sind davon \u00fcberzeugt, dass der Schutz der <strong>Umwelt<\/strong> f\u00fcr die Zukunft des Tourismus unerl\u00e4sslich ist. Deshalb haben wir unsere internen Prozesse neu gestaltet, nach <strong>innovativen L\u00f6sungen<\/strong> gesucht und nachhaltige Alternativen eingef\u00fchrt, die unsere Mitarbeiter, Partner und Lieferanten gleicherma\u00dfen einbeziehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nachhaltigkeitsergebnisse und KPIs bei RIU (2021\u20132025)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um die tats\u00e4chlichen Auswirkungen unserer Umweltpolitik zu messen, \u00fcberwachen wir Kennzahlen, die unseren \u00dcbergang zu einem plastikfreien Modell widerspiegeln.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><th><strong>KPI-Indikator<\/strong><\/th><th><strong>Ergebnis \/ Ma\u00dfnahme<\/strong><\/th><\/tr><tr><td><strong>Reduzierung von Einwegplastik<\/strong><\/td><td><strong>-27,7 %<\/strong> pro Aufenthalt seit 2021<\/td><\/tr><tr><td><strong>Amenities in den Zimmern<\/strong><\/td><td>Ersatz durch nachf\u00fcllbare Spender im Gro\u00dfformat<\/td><\/tr><tr><td><strong>Nachhaltige Gastronomie<\/strong><\/td><td>Verzicht auf Plastikstrohhalme zugunsten von Papieralternativen<\/td><\/tr><tr><td><strong>Lieferantenmanagement<\/strong><\/td><td>Verpflichtende Einhaltung von Standards zur Plastikreduzierung<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Wichtigste Erkenntnis:<\/strong> Der Erfolg von RIU bei der Reduzierung von Plastikabf\u00e4llen liegt in der Integration von Nachhaltigkeit in den t\u00e4glichen Hotelbetrieb und der Sensibilisierung aller Teams.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Video: Nachhaltigkeitsma\u00dfnahmen in unseren Hotels<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Da Bilder mehr sagen als Worte, haben wir visuelle Inhalte vorbereitet, die den Wandel unserer Dienstleistungen erl\u00e4utern.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"International Environment Day at RIU\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/NSbaIIZ8wXs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Sensibilisierungsma\u00dfnahmen werden in den Hotels durchgef\u00fchrt?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Engagement von RIU geht \u00fcber das operative Management hinaus; wir m\u00f6chten einen positiven Einfluss auf unsere G\u00e4ste und die lokalen Gemeinschaften aus\u00fcben. Zum <strong>Weltumwelttag<\/strong> aktivieren unsere Nachhaltigkeitsabteilungen spezielle Programme:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Workshops f\u00fcr Kinder:<\/strong> P\u00e4dagogische Aktivit\u00e4ten f\u00fcr Kinder \u00fcber Recycling und den Schutz der Ozeane in unserem RiuLand Club.<\/li>\n\n\n\n<li><strong>Umweltreinigungen:<\/strong> Aktionstage zur Abfallsammlung an Str\u00e4nden und in Naturgebieten in der N\u00e4he unserer <a href=\"https:\/\/www.riu.com\/de\/home.jsp\" target=\"_blank\" rel=\"noreferrer noopener\">Hotels in Strandzielen<\/a>.<\/li>\n\n\n\n<li><strong>Digitale Sensibilisierung:<\/strong> Wir laden unsere G\u00e4ste ein, ihre Ma\u00dfnahmen unter den Hashtags #ProudlyCommitted und #BeatPlasticPollution zu teilen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bei <strong>RIU<\/strong> sind davon \u00fcberzeugt, dass der perfekte Urlaub derjenige ist, der einen minimalen Fu\u00dfabdruck auf dem Planeten, aber einen riesigen Eindruck in den Herzen unserer G\u00e4ste hinterl\u00e4sst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bereit f\u00fcr einen nachhaltigen, plastikfreien Urlaub?<\/strong> <a href=\"https:\/\/www.riu.com\/de\/home.jsp\" target=\"_blank\" rel=\"noreferrer noopener\">Buchen Sie hier Ihren Aufenthalt bei RIU Hotels<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">H\u00e4ufig gestellte Fragen (FAQ) zum Weltumwelttag<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Was ist die Initiative #BeatPlasticPollution?<\/strong> Es handelt sich um eine globale Bewegung unter der Leitung der <a href=\"https:\/\/www.worldenvironmentday.global\/\">Vereinten Nationen<\/a>, um die Krise der Plastikverschmutzung durch kollektives Handeln und kreislauforientierte L\u00f6sungen zu bek\u00e4mpfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Wo kann ich die Ma\u00dfnahmen von RIU gegen Plastik sehen?<\/strong> Sie k\u00f6nnen alle unsere Initiativen im offiziellen Video auf unserem YouTube-Kanal ansehen oder unseren Bereich <a href=\"https:\/\/www.google.com\/search?q=https:\/\/www.riu.com\/de\/verantwortungsbewusstes-handeln\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nachhaltigkeit<\/a> besuchen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Wie hat RIU Plastik in den G\u00e4stezimmern reduziert?<\/strong> RIU hat Einweg-Einzelbeh\u00e4lter (Mini-Amenities) eliminiert und durch fest installierte, nachf\u00fcllbare Gel- und Shampoospender ersetzt sowie Plastikflaschen und -becher entfernt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4. Was k\u00f6nnen G\u00e4ste w\u00e4hrend ihres Aufenthalts tun?<\/strong> G\u00e4ste k\u00f6nnen an geplanten Reinigungsaktionen teilnehmen, die Recyclingstationen des Hotels nutzen und auf Einwegprodukte verzichten, wenn sie die \u00f6rtlichen Str\u00e4nde besuchen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><br><br><br><br><br><br><br><br><br><br><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"RIU Hotels schlie\u00dft sich am 5. Juni 2025 der UN-Kampagne #BeatPlasticPollution an und bekr\u00e4ftigt damit sein Engagement f\u00fcr den nachhaltigen Tourismus. Durch die Strategie Proudly Committed hat die Kette seit 2021 eine Reduzierung von Einwegkunststoffen um 27,7 % pro Aufenthalt erreicht, indem sie Einweg-Amenities eliminiert und ihre Lieferkette optimiert hat. Was beinhaltet das Engagement von&#8230;","protected":false},"author":3,"featured_media":37897,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2253],"tags":[],"class_list":["post-37859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proudly-committed"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIU Hotels: Strategie #BeatPlasticPollution &amp; Nachhaltigkeit 2025<\/title>\n<meta name=\"description\" content=\"Erfahren Sie, wie RIU Hotels zum Weltumwelttag den Einwegplastikverbrauch um 27,7 % gesenkt hat. Sehen Sie das Video und buchen Sie nachhaltig!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIU Hotels: Strategie #BeatPlasticPollution &amp; Nachhaltigkeit 2025\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie, wie RIU Hotels zum Weltumwelttag den Einwegplastikverbrauch um 27,7 % gesenkt hat. Sehen Sie das Video und buchen Sie nachhaltig!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"RIU.com | Blog\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T12:46:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T15:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/iStock-1808148077.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2449\" \/>\n\t<meta property=\"og:image:height\" content=\"1378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Riu Hotels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Riu Hotels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/\"},\"author\":{\"name\":\"Riu Hotels\",\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/37a64b13d864caf556d86f6ef0da8e10\"},\"headline\":\"Wie bek\u00e4mpft RIU Hotels die Plastikverschmutzung am Weltumwelttag?\",\"datePublished\":\"2025-06-05T12:46:02+00:00\",\"dateModified\":\"2026-02-26T15:03:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/\"},\"wordCount\":559,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/iStock-1808148077.jpg\",\"articleSection\":[\"Proudly Committed\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/\",\"url\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/\",\"name\":\"RIU Hotels: Strategie #BeatPlasticPollution & Nachhaltigkeit 2025\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/iStock-1808148077.jpg\",\"datePublished\":\"2025-06-05T12:46:02+00:00\",\"dateModified\":\"2026-02-26T15:03:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/37a64b13d864caf556d86f6ef0da8e10\"},\"description\":\"Erfahren Sie, wie RIU Hotels zum Weltumwelttag den Einwegplastikverbrauch um 27,7 % gesenkt hat. Sehen Sie das Video und buchen Sie nachhaltig!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/iStock-1808148077.jpg\",\"contentUrl\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/iStock-1808148077.jpg\",\"width\":2449,\"height\":1378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie bek\u00e4mpft RIU Hotels die Plastikverschmutzung am Weltumwelttag?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/\",\"name\":\"RIU.com | Blog\",\"description\":\"Blog de Riu Hotels &amp; Resorts | Noticias exclusivas de la cadena Riu Hotels &amp; Resor.ts | Hoteles en Espa\u00f1a, M\u00e9xico, Jamaica, Rep\u00fablica Dominicana, Portugal, Miami y muchos m\u00e1s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/#\\\/schema\\\/person\\\/37a64b13d864caf556d86f6ef0da8e10\",\"name\":\"Riu Hotels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1845185f5dc0c5d7a3adb797bcd6cae1d3df26e3eead5da96b212485b274bdf3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1845185f5dc0c5d7a3adb797bcd6cae1d3df26e3eead5da96b212485b274bdf3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1845185f5dc0c5d7a3adb797bcd6cae1d3df26e3eead5da96b212485b274bdf3?s=96&d=mm&r=g\",\"caption\":\"Riu Hotels\"},\"url\":\"https:\\\/\\\/www.riu.com\\\/blog\\\/de\\\/author\\\/riu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIU Hotels: Strategie #BeatPlasticPollution & Nachhaltigkeit 2025","description":"Erfahren Sie, wie RIU Hotels zum Weltumwelttag den Einwegplastikverbrauch um 27,7 % gesenkt hat. Sehen Sie das Video und buchen Sie nachhaltig!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/","og_locale":"de_DE","og_type":"article","og_title":"RIU Hotels: Strategie #BeatPlasticPollution & Nachhaltigkeit 2025","og_description":"Erfahren Sie, wie RIU Hotels zum Weltumwelttag den Einwegplastikverbrauch um 27,7 % gesenkt hat. Sehen Sie das Video und buchen Sie nachhaltig!","og_url":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/","og_site_name":"RIU.com | Blog","article_published_time":"2025-06-05T12:46:02+00:00","article_modified_time":"2026-02-26T15:03:04+00:00","og_image":[{"width":2449,"height":1378,"url":"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/iStock-1808148077.jpg","type":"image\/jpeg"}],"author":"Riu Hotels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Riu Hotels","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#article","isPartOf":{"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/"},"author":{"name":"Riu Hotels","@id":"https:\/\/www.riu.com\/blog\/de\/#\/schema\/person\/37a64b13d864caf556d86f6ef0da8e10"},"headline":"Wie bek\u00e4mpft RIU Hotels die Plastikverschmutzung am Weltumwelttag?","datePublished":"2025-06-05T12:46:02+00:00","dateModified":"2026-02-26T15:03:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/"},"wordCount":559,"commentCount":0,"image":{"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/iStock-1808148077.jpg","articleSection":["Proudly Committed"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/","url":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/","name":"RIU Hotels: Strategie #BeatPlasticPollution & Nachhaltigkeit 2025","isPartOf":{"@id":"https:\/\/www.riu.com\/blog\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/iStock-1808148077.jpg","datePublished":"2025-06-05T12:46:02+00:00","dateModified":"2026-02-26T15:03:04+00:00","author":{"@id":"https:\/\/www.riu.com\/blog\/de\/#\/schema\/person\/37a64b13d864caf556d86f6ef0da8e10"},"description":"Erfahren Sie, wie RIU Hotels zum Weltumwelttag den Einwegplastikverbrauch um 27,7 % gesenkt hat. Sehen Sie das Video und buchen Sie nachhaltig!","breadcrumb":{"@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#primaryimage","url":"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/iStock-1808148077.jpg","contentUrl":"https:\/\/www.riu.com\/blog\/wp-content\/uploads\/2025\/06\/iStock-1808148077.jpg","width":2449,"height":1378},{"@type":"BreadcrumbList","@id":"https:\/\/www.riu.com\/blog\/de\/riu-hotels-beat-plastic-pollution-strategie-nachhaltigkeit-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.riu.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Wie bek\u00e4mpft RIU Hotels die Plastikverschmutzung am Weltumwelttag?"}]},{"@type":"WebSite","@id":"https:\/\/www.riu.com\/blog\/de\/#website","url":"https:\/\/www.riu.com\/blog\/de\/","name":"RIU.com | Blog","description":"Blog de Riu Hotels &amp; Resorts | Noticias exclusivas de la cadena Riu Hotels &amp; Resor.ts | Hoteles en Espa\u00f1a, M\u00e9xico, Jamaica, Rep\u00fablica Dominicana, Portugal, Miami y muchos m\u00e1s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.riu.com\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.riu.com\/blog\/de\/#\/schema\/person\/37a64b13d864caf556d86f6ef0da8e10","name":"Riu Hotels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1845185f5dc0c5d7a3adb797bcd6cae1d3df26e3eead5da96b212485b274bdf3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1845185f5dc0c5d7a3adb797bcd6cae1d3df26e3eead5da96b212485b274bdf3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1845185f5dc0c5d7a3adb797bcd6cae1d3df26e3eead5da96b212485b274bdf3?s=96&d=mm&r=g","caption":"Riu Hotels"},"url":"https:\/\/www.riu.com\/blog\/de\/author\/riu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/posts\/37859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=37859"}],"version-history":[{"count":6,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/posts\/37859\/revisions"}],"predecessor-version":[{"id":41275,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/posts\/37859\/revisions\/41275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/media\/37897"}],"wp:attachment":[{"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=37859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=37859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.riu.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=37859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}